{"id":1179,"date":"2020-03-07T10:39:05","date_gmt":"2020-03-07T13:39:05","guid":{"rendered":"https:\/\/elfederalmendoza.com\/?p=1179"},"modified":"2020-03-07T10:39:05","modified_gmt":"2020-03-07T13:39:05","slug":"cayo-el-presunto-asesino-del-joven-peluquero-asesinado-en-ciudad","status":"publish","type":"post","link":"https:\/\/elfederalmendoza.com.ar\/index.php\/2020\/03\/07\/cayo-el-presunto-asesino-del-joven-peluquero-asesinado-en-ciudad\/","title":{"rendered":"Cay\u00f3 el presunto asesino del joven peluquero asesinado en Ciudad"},"content":{"rendered":"<div class=\"media\">\n<div class=\"image\">\n<div class=\"zoom\"><\/div>\n<\/div>\n<\/div>\n<div id=\"vsmcontent\" class=\"content vsmcontent\">\n<figure id=\"vsmv37381v25\" class=\"vsmimage red60 floatright\" contenteditable=\"false\"><img loading=\"lazy\" decoding=\"async\" id=\"vsmv37381v24\" contenteditable=\"false\" src=\"https:\/\/www.sitioandino.com.ar\/files\/image\/427\/427641\/5e62dc874efb8_501_668!.jpg?s=66008cce3e254bae1813f1c8df31e360&amp;d=1583537291\" width=\"501\" height=\"668\" data-vsmid=\"427641\" data-owidth=\"774\" data-oheight=\"1032\" \/><figcaption>El sospechoso, Eduardo Emanuel Tobares (24).<\/p>\n<\/figcaption><\/figure>\n<p>La Divisi\u00f3n Homicidios detuvo esta tarde al presunto autor del\u00a0asesinato de\u00a0 arcelo Paredes (21), el joven peluquero que fue asesinado durante un asalto en cuidad<\/p>\n<p>El sospechoso, Eduardo Emanuel Tobares (24), fue capturado en el interior del barrio Escorihuela de Ciudad, quien ya hab\u00eda sido se\u00f1alado por testigos como uno de los responsables del crimen.<\/p>\n<p>Fuentes policiales dijeron que el sospechoso era seguido de cerca por los sabuesos y que esta tarde fue encontrado en inmediaciones a la manzana D del barrio capitalino.<\/p>\n<p>El sospechoso fue llevado a la Comisar\u00eda Sexta, donde qued\u00f3 detenido a disposici\u00f3n del fiscal Carlos Torres.<\/p>\n<p>Por el momento, no trascendi\u00f3 si la captura se concret\u00f3 gracias a un llamado por la\u00a0recompensa de $200.000 que odrecia el ministerio de seguridad para atrapar al autor del crimen<\/p>\n<p>\u00abAhito\u00bb Paredes, un joven de 19 a\u00f1os que ten\u00eda una barber\u00eda en Ciudad, fue asesinado\u00a0durante un asalto ocurrido el viernes 21 de febrero por la noche en el barrio la favorita<\/p>\n<p>La reconstrucci\u00f3n del hecho se\u00f1ala que el joven fue abordado por dos sujetos que intentaron robarle el poco dinero que ten\u00eda consigo. En medio del atraco, uno de los maleantes le dispar\u00f3 en el t\u00f3rax, herida que luego provoc\u00f3 su fallecimiento en el hospital.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El sospechoso, Eduardo Emanuel Tobares (24). La Divisi\u00f3n Homicidios detuvo esta tarde al presunto autor del\u00a0asesinato de\u00a0 arcelo Paredes (21), el joven peluquero que fue asesinado durante un asalto en cuidad El sospechoso, Eduardo Emanuel Tobares (24), fue capturado en el interior del barrio Escorihuela de Ciudad, quien ya hab\u00eda sido se\u00f1alado por testigos como<a class=\"read-more\" href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/2020\/03\/07\/cayo-el-presunto-asesino-del-joven-peluquero-asesinado-en-ciudad\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":1180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[1],"tags":[122,11],"class_list":["post-1179","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-mza","tag-asesinato","tag-mendoza","post_format-post-format-image"],"rttpg_featured_image_url":{"full":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607.jpg",896,607,false],"landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607.jpg",896,607,false],"portraits":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607.jpg",896,607,false],"thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607-150x150.jpg",150,150,true],"medium":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607-300x203.jpg",300,203,true],"large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607.jpg",640,434,false],"1536x1536":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607.jpg",896,607,false],"2048x2048":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607.jpg",896,607,false],"ultp_layout_landscape_large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607.jpg",896,607,false],"ultp_layout_landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607.jpg",841,570,false],"ultp_layout_portrait":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607.jpg",600,406,false],"ultp_layout_square":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607.jpg",600,406,false],"rpwe-thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607-45x45.jpg",45,45,true],"advps-thumb-one":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2020\/03\/5e582514beec4_896_607-896x420.jpg",896,420,true]},"rttpg_author":{"display_name":"Redacci\u00f3n El Federal","author_link":"https:\/\/elfederalmendoza.com.ar\/index.php\/author\/angelflores\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/category\/mza\/\" rel=\"category tag\">Mendoza<\/a>","rttpg_excerpt":"El sospechoso, Eduardo Emanuel Tobares (24). La Divisi\u00f3n Homicidios detuvo esta tarde al presunto autor del\u00a0asesinato de\u00a0 arcelo Paredes (21), el joven peluquero que fue asesinado durante un asalto en cuidad El sospechoso, Eduardo Emanuel Tobares (24), fue capturado en el interior del barrio Escorihuela de Ciudad, quien ya hab\u00eda sido se\u00f1alado por testigos como&hellip;","_links":{"self":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=1179"}],"version-history":[{"count":1,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1179\/revisions"}],"predecessor-version":[{"id":1181,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1179\/revisions\/1181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media\/1180"}],"wp:attachment":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=1179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=1179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=1179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}