{"id":18512,"date":"2022-07-27T10:46:39","date_gmt":"2022-07-27T13:46:39","guid":{"rendered":"https:\/\/elfederalmendoza.com\/?p=18512"},"modified":"2022-07-27T10:46:41","modified_gmt":"2022-07-27T13:46:41","slug":"si-un-alumno-falta-y-el-docente-no-hace-paro-la-falta-sera-injustificada","status":"publish","type":"post","link":"https:\/\/elfederalmendoza.com.ar\/index.php\/2022\/07\/27\/si-un-alumno-falta-y-el-docente-no-hace-paro-la-falta-sera-injustificada\/","title":{"rendered":"Si un alumno falta y el docente no hace paro, la falta ser\u00e1 injustificada"},"content":{"rendered":"\n<p>En el\u00a0<strong>segundo d\u00eda de la medida de fuerza gremial<\/strong>\u00a0encabezada por los docentes provinciales en reclamo por una\u00a0<strong>recomposici\u00f3n salarial,<\/strong>\u00a0desde la\u00a0<strong>Direcci\u00f3n General de Escuelas (DGE)\u00a0<\/strong>difundieron la\u00a0<strong>circular<\/strong>\u00a0N\u00b013-2022 para aclarar el panorama en torno a lo que pasar\u00e1 con las\u00a0<strong>faltas de los estudiantes.<\/strong><\/p>\n\n\n\n<p>De esta manera, y antes de que comience a regir el segundo d\u00eda de paro, la&nbsp;<strong>DGE<\/strong>&nbsp;envi\u00f3 una circular en la que establece que si este mi\u00e9rcoles el&nbsp;<strong>docente no hace huelga<\/strong>, el&nbsp;<strong>alumno<\/strong>&nbsp;que est\u00e9 ausente tendr\u00e1 falta injustificada.<\/p>\n\n\n\n<p>\u00abLa circular recibida establece que se colocar\u00e1, en el caso que el docente adhiera al paro, ausente justificado al alumno. Y en el caso que el docente no adhiera, pero el estudiante no asista, se colocar\u00e1 ausente injustificado\u00bb, especifica el comunicado difundido este martes.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/398\/398777\/62dfd6fe4d173_570_299!.jpg?s=7644200a3f8f88ec765de6d820a77860&amp;d=1658845245\" alt=\"\" width=\"1223\" height=\"642\"\/><figcaption>En el segundo d\u00eda de paro, la falta de los alumnos se justificar\u00e1n si el docente falta.&nbsp;<\/figcaption><\/figure>\n\n\n\n<p>As\u00ed, la\u00a0<strong>DGE<\/strong>, confirm\u00f3 que el criterio a seguir ser\u00e1 el indicado en dicha\u00a0<strong>circular<\/strong>\u00a0en el marco del\u00a0<strong>segundo d\u00eda de huelga<\/strong>, y tal como ocurri\u00f3 a principios de semana, se multiplicaron las instituciones -incluso de gesti\u00f3n privada- que anticiparon un alto acatamiento<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/398\/398909\/62dffbf2e777e_570_428!.jpg?s=71dd05c9306ff4189dbe3ef8a49ea57d&amp;d=1658848457\" alt=\"\" width=\"1218\" height=\"915\"\/><figcaption>LA DGE envi\u00f3 una circular a las escuelas por la inasistencia.&nbsp;<\/figcaption><\/figure>\n\n\n\n<p>Por otra parte, y pese a que en numerosas escuelas se mostraron con\u00a0<strong>aulas vac\u00edas<\/strong>, el Gobierno provincial asegura que el\u00a0<strong>acatamiento al paro fue del 32%<\/strong>\u00a0asegurando que estas estimaciones tienen su correlato a trav\u00e9s del\u00a0<strong>Sistema de Gesti\u00f3n Educativa Mendoza (GEM).<\/strong><\/p>\n\n\n\n<p><strong>Mendoza Post<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el\u00a0segundo d\u00eda de la medida de fuerza gremial\u00a0encabezada por los docentes provinciales en reclamo por una\u00a0recomposici\u00f3n salarial,\u00a0desde la\u00a0Direcci\u00f3n General de Escuelas (DGE)\u00a0difundieron la\u00a0circular\u00a0N\u00b013-2022 para aclarar el panorama en torno a lo que pasar\u00e1 con las\u00a0faltas de los estudiantes. De esta manera, y antes de que comience a regir el segundo d\u00eda de paro, la&nbsp;DGE&nbsp;envi\u00f3<a class=\"read-more\" href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/2022\/07\/27\/si-un-alumno-falta-y-el-docente-no-hace-paro-la-falta-sera-injustificada\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":18513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mza"],"rttpg_featured_image_url":{"full":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es.webp",1024,440,false],"landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es.webp",1024,440,false],"portraits":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es.webp",1024,440,false],"thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es-150x150.webp",150,150,true],"medium":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es-300x129.webp",300,129,true],"large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es.webp",640,275,false],"1536x1536":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es.webp",1024,440,false],"2048x2048":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es.webp",1024,440,false],"ultp_layout_landscape_large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es.webp",1024,440,false],"ultp_layout_landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es-870x440.webp",870,440,true],"ultp_layout_portrait":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es-600x440.webp",600,440,true],"ultp_layout_square":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es-600x440.webp",600,440,true],"rpwe-thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es-45x45.webp",45,45,true],"advps-thumb-one":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/07\/es-1024x420.webp",1024,420,true]},"rttpg_author":{"display_name":"Redacci\u00f3n El Federal","author_link":"https:\/\/elfederalmendoza.com.ar\/index.php\/author\/angelflores\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/category\/mza\/\" rel=\"category tag\">Mendoza<\/a>","rttpg_excerpt":"En el\u00a0segundo d\u00eda de la medida de fuerza gremial\u00a0encabezada por los docentes provinciales en reclamo por una\u00a0recomposici\u00f3n salarial,\u00a0desde la\u00a0Direcci\u00f3n General de Escuelas (DGE)\u00a0difundieron la\u00a0circular\u00a0N\u00b013-2022 para aclarar el panorama en torno a lo que pasar\u00e1 con las\u00a0faltas de los estudiantes. De esta manera, y antes de que comience a regir el segundo d\u00eda de paro, la&nbsp;DGE&nbsp;envi\u00f3&hellip;","_links":{"self":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/18512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=18512"}],"version-history":[{"count":1,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/18512\/revisions"}],"predecessor-version":[{"id":18514,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/18512\/revisions\/18514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media\/18513"}],"wp:attachment":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=18512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=18512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=18512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}