{"id":18949,"date":"2022-08-29T13:48:27","date_gmt":"2022-08-29T16:48:27","guid":{"rendered":"https:\/\/elfederalmendoza.com\/?p=18949"},"modified":"2022-08-29T13:51:20","modified_gmt":"2022-08-29T16:51:20","slug":"tadeo-garcia-zalazar-el-kirchnerismo-esta-tirando-de-la-cuerda","status":"publish","type":"post","link":"https:\/\/elfederalmendoza.com.ar\/index.php\/2022\/08\/29\/tadeo-garcia-zalazar-el-kirchnerismo-esta-tirando-de-la-cuerda\/","title":{"rendered":"Tadeo Garc\u00eda Zalazar: \u00abEl kirchnerismo est\u00e1 tirando de la cuerda\u00bb"},"content":{"rendered":"\n<p>La municipalidad de&nbsp;<strong>Godoy Cruz<\/strong>&nbsp;y la de<strong>&nbsp;Guaymall\u00e9n<\/strong>&nbsp;inauguraron este lunes un&nbsp;<strong>parque lineal interdepartamental&nbsp;<\/strong>que nace desde atr\u00e1s de la cancha del Tomba, donde se ubica el Parque Mitre y desde ah\u00ed, va paralelo a las v\u00edas del tren, finalizando en la estaci\u00f3n Progreso del Metrotranv\u00eda, del lado de la comuna comandada por Marcelino Iglesias.<\/p>\n\n\n\n<p>En di\u00e1logo con el programa&nbsp;<em><strong>Te digo lo que pienso&nbsp;<\/strong><\/em>que conduce Ricardo Montacuto por Radio Nihuil, el intendente&nbsp;<strong>Tadeo Garc\u00eda Zalazar<\/strong>&nbsp;dijo que en el lugar han realizado una ciclov\u00eda con iluminaci\u00f3n y espacios verdes. \u00abAhora vamos a plantar \u00e1rboles con chicos de escuelas de los dos departamentos. Son m\u00e1s de&nbsp;<strong>600 metros lineales<\/strong>. Es una v\u00eda que se abre, porque eso era un gran basural y es un espacio que hemos recuperado\u00bb.<\/p>\n\n\n\n<p>\u00abLa idea es que sirva de conexi\u00f3n entre las dos comunas. La gente que venga desde el Boulevard Dorrego, va a poder tomar la ciclov\u00eda\u00a0 que pasa\u00a0por debajo de la Costanera y cruza el canal Cacique Guaymall\u00e9n por un puente nuevo que hemos hecho para el cruce peatonal y de bicicletas. El fin de semana,\u00a0 vamos a poner Food Trucks. Adem\u00e1s, habr\u00e1 distintas actividades, como ferias de artesanos, cuando empiecen los d\u00edas m\u00e1s c\u00e1lidos\u00bb, anunci\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/396\/396003\/62d2892d1c553_570_404!.jpg?s=4b176b5863c5542030a4c98b85abc014&amp;d=1661785353\" alt=\"\" width=\"1132\" height=\"802\"\/><\/figure>\n\n\n\n<p>Tadeo Garc\u00eda Zalazar<\/p>\n\n\n\n<p><strong>Manifestaciones en apoyo a CFK<\/strong><\/p>\n\n\n\n<p>Al respecto, el presidente de la UCR Mendoza dijo: \u00abNos parece que hay una necesidad de mantener la paz social y de que esta situaci\u00f3n transite en el mejor de los climas posibles. Lo que pasa es que todo el tiempo,&nbsp;<strong>el kirchnerismo est\u00e1 tirando de la cuerda<\/strong>. Cuando la Justicia falla a favor de Cristina no dicen nada,&nbsp; pero cuando falla en contra, para ellos hay lawfare o injerencia pol\u00edtica en la justicia\u00bb, indic\u00f3.<\/p>\n\n\n\n<p>\u00abSiempre tienen su propia parte del relato. Lo mismo pas\u00f3 con todas las manifestaciones y me parece que est\u00e1 todo armado como para incomodar a Rodr\u00edguez Larreta;&nbsp; para dejarlo mal parado y tratando de vincular eso con el tema judicial que tiene la vicepresidenta, que la verdad, es escandaloso. Ojal\u00e1 la Justicia act\u00fae r\u00e1pidamente. Todo se encamina hacia las evidencias que se han presentado (caso Vialidad) y que son irrefutables. Pero el relato kirchnerista trata todo el tiempo de imponer su propia realidad y me parece que la gente ya entendi\u00f3 que no es as\u00ed. Por ahora, lo que se ha visto es un intento desesperado de mantener ese status quo de impunidad que tiene CFK\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/409\/409841\/630c3700538af_570_376!.jpg?s=a27026407aefcbac7dd23ead0b4665b7&amp;d=1661785475\" alt=\"\" width=\"1119\" height=\"738\"\/><\/figure>\n\n\n\n<p>Relaci\u00f3n gente-clase pol\u00edtica<\/p>\n\n\n\n<p>Al respecto, el intendente de Godoy cruz reconoci\u00f3 que la relaci\u00f3n en general est\u00e1 tensa. \u00abCreo que mientras m\u00e1s alejada de los centros de poder, m\u00e1s tensa es la relaci\u00f3n con la gente. En los municipios, la relaci\u00f3n con nuestros vecinos es m\u00e1s cotidiana y tiene que ver con temas espec\u00edficos, como es el caso de los servicios. Pero, inclusive en esa agenda local, est\u00e1 siempre presente la preocupaci\u00f3n de la gente por el tema econ\u00f3mico, inflaci\u00f3n y desempleo que son cosas que se empiezan a ver en la ciudadan\u00eda\u00bb, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>En esa l\u00ednea, remarc\u00f3 que \u00abesos temas mal predisponen y generan \u00e1nimos de climas no positivos en la gente. Creo que hay que trabajar mucho en ver c\u00f3mo nosotros le ponemos lo mejor a la relaci\u00f3n para que los vecinos la pasen un poco mejor. Lo que s\u00ed, en esto la responsabilidad es del gobierno nacional, porque ni las provincias ni los municipios tenemos injerencia en la pol\u00edtica monetaria ni en las tasas de inter\u00e9s,&nbsp; ni&nbsp; en la emisi\u00f3n. Tanto la provincia como los municipios gobernados por Cambia Mendoza, en general, tenemos gestiones muy ordenadas, con super\u00e1vit,&nbsp; donde se pagan los sueldos, cosa que no est\u00e1 pasando en otras provincias\u00bb, advirti\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/405\/405353\/62fa7cae6ae80_570_291!.jpg?s=b273a1c0ce78ce43b711a8b3a982e6a8&amp;d=1661785548\" alt=\"\" width=\"1128\" height=\"576\"\/><\/figure>\n\n\n\n<p>Qu\u00e9 hacer con la mitad de dinero de Portezuelo<\/p>\n\n\n\n<p>El radical dijo que, a su entender, Mendoza deber\u00eda ser aut\u00f3noma y entrar directamente a un plan de inversi\u00f3n con obras virtuosas, que generen alg\u00fan tipo de retorno, como las obras el\u00e9ctricas que generan un ingreso para la provincia. \u00abIrrigaci\u00f3n tambi\u00e9n est\u00e1 trabajando en un master plan con los israel\u00edes, con dos escenarios a 2030 y 2040 para poder hacer inversiones que tienen que ver con obras de riego y tambi\u00e9n para el consumo de agua de la poblaci\u00f3n y reutilizaci\u00f3n\u00bb.<\/p>\n\n\n\n<p>Por \u00faltimo, destac\u00f3 que en Godoy Cruz \u00abestamos haciendo algunas experiencias de riego con reutilizaci\u00f3n de agua, es menos del 5%. Pero, con el sector privado, tenemos una ordenanza que se refiere a la reutilizaci\u00f3n de aguas grises en las nuevas construcciones y est\u00e1 funcionando muy bien\u00bb, finaliz\u00f3.<\/p>\n\n\n\n<p><strong>Mendoza Post<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La municipalidad de&nbsp;Godoy Cruz&nbsp;y la de&nbsp;Guaymall\u00e9n&nbsp;inauguraron este lunes un&nbsp;parque lineal interdepartamental&nbsp;que nace desde atr\u00e1s de la cancha del Tomba, donde se ubica el Parque Mitre y desde ah\u00ed, va paralelo a las v\u00edas del tren, finalizando en la estaci\u00f3n Progreso del Metrotranv\u00eda, del lado de la comuna comandada por Marcelino Iglesias. En di\u00e1logo con el<a class=\"read-more\" href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/2022\/08\/29\/tadeo-garcia-zalazar-el-kirchnerismo-esta-tirando-de-la-cuerda\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":18950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mza"],"rttpg_featured_image_url":{"full":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo.jpg",1068,594,false],"landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo.jpg",1068,594,false],"portraits":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo.jpg",1068,594,false],"thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo-150x150.jpg",150,150,true],"medium":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo-300x167.jpg",300,167,true],"large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo-1024x570.jpg",640,356,true],"1536x1536":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo.jpg",1068,594,false],"2048x2048":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo.jpg",1068,594,false],"ultp_layout_landscape_large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo.jpg",1068,594,false],"ultp_layout_landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo-870x570.jpg",870,570,true],"ultp_layout_portrait":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo-600x594.jpg",600,594,true],"ultp_layout_square":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo-600x594.jpg",600,594,true],"rpwe-thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo-45x45.jpg",45,45,true],"advps-thumb-one":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2022\/08\/tadeo-1068x420.jpg",1068,420,true]},"rttpg_author":{"display_name":"Redacci\u00f3n El Federal","author_link":"https:\/\/elfederalmendoza.com.ar\/index.php\/author\/angelflores\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/category\/mza\/\" rel=\"category tag\">Mendoza<\/a>","rttpg_excerpt":"La municipalidad de&nbsp;Godoy Cruz&nbsp;y la de&nbsp;Guaymall\u00e9n&nbsp;inauguraron este lunes un&nbsp;parque lineal interdepartamental&nbsp;que nace desde atr\u00e1s de la cancha del Tomba, donde se ubica el Parque Mitre y desde ah\u00ed, va paralelo a las v\u00edas del tren, finalizando en la estaci\u00f3n Progreso del Metrotranv\u00eda, del lado de la comuna comandada por Marcelino Iglesias. En di\u00e1logo con el&hellip;","_links":{"self":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/18949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=18949"}],"version-history":[{"count":1,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/18949\/revisions"}],"predecessor-version":[{"id":18951,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/18949\/revisions\/18951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media\/18950"}],"wp:attachment":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=18949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=18949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=18949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}