{"id":24370,"date":"2023-06-22T17:55:01","date_gmt":"2023-06-22T20:55:01","guid":{"rendered":"https:\/\/elfederalmendoza.com\/?p=24370"},"modified":"2023-06-22T17:59:59","modified_gmt":"2023-06-22T20:59:59","slug":"oceangate-que-confirma-la-muerte-de-los-cinco-tripulantes-del-submarino-titan","status":"publish","type":"post","link":"https:\/\/elfederalmendoza.com.ar\/index.php\/2023\/06\/22\/oceangate-que-confirma-la-muerte-de-los-cinco-tripulantes-del-submarino-titan\/","title":{"rendered":"OceanGate confirm\u00f3 la muerte de los cinco tripulantes del submarino Titan"},"content":{"rendered":"\n<p>La empresa OceanGate emiti\u00f3 un comunicado en el que confirm\u00f3 que los cinco tripulantes de Titan, el sumergible que estaba desaparecido desde el domingo, est\u00e1n&nbsp;<strong>muertos.<\/strong><\/p>\n\n\n\n<p><strong>\u201cLamentablemente creemos que hemos perdido a nuestro CEO, Stockton Rush, a Shahzada Dawood y a su hijo Suleman Dawood, a Hamish Harding y a Paul-Henri Nargeolet\u201d, se\u00f1al\u00f3 la empresa\u201d<\/strong>, comienza el texto difundido por la compa\u00f1\u00eda.<\/p>\n\n\n\n<p>Prosigue diciendo que \u201cestos hombres eran verdaderos exploradores que compart\u00edan un esp\u00edritu distintivo de aventura y una profunda pasi\u00f3n por explorar y proteger los oc\u00e9anos del mundo. Nuestros corazones est\u00e1n con estas cinco almas y cada miembro de sus familias durante este tr\u00e1gico momento. Lamentamos la p\u00e9rdida de vidas y la alegr\u00eda que trajeron a todos los que conoc\u00edan\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/elfederalmendoza.com\/wp-content\/uploads\/2023\/06\/oceangate5.jpg\" alt=\"\" class=\"wp-image-24375\" width=\"833\" height=\"556\" srcset=\"https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate5.jpg 691w, https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate5-300x200.jpg 300w\" sizes=\"auto, (max-width: 833px) 100vw, 833px\" \/><figcaption class=\"wp-element-caption\">El contralmirante John Mauger del Primer Distrito de la Guardia Costera (REUTERS\/Brian Snyder)<\/figcaption><\/figure>\n\n\n\n<p>Contin\u00faa diciendo que \u00e9ste es un momento \u201cextremadamente triste para nuestros dedicados empleados que est\u00e1n exhaustos y afligidos profundamente por esta p\u00e9rdida. Toda la familia de Ocean Gate est\u00e1 profundamente agradecida por los innumerables hombres y mujeres de m\u00faltiples organizaciones de la comunidad internacional que agilizaron una amplia variedad de recursos y trabajaron arduamente en esta misi\u00f3n. Agradecemos su compromiso de encontrar a estos cinco exploradores y sus d\u00edas y noches de trabajo incansable en apoyo de nuestra tripulaci\u00f3n y sus familias\u201d.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Los tripulantes\" height=\"1080\" width=\"1920\" class=\"\" src=\"https:\/\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/KQCE5SO2EZB2BDG5UZYXFOD46Q.jpg\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/5Y3GGnRLj7cwqFp9-iKvmj3v5J0=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/KQCE5SO2EZB2BDG5UZYXFOD46Q.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/31c4drqSyNIDgvgtXGLMaA-bA50=\/768x432\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/KQCE5SO2EZB2BDG5UZYXFOD46Q.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/M-XKMJLyKRRKVMZh3oPan7nVO2Q=\/992x558\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/KQCE5SO2EZB2BDG5UZYXFOD46Q.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/L4RG9Xvz6IGAHeXgEv38hnL33pw=\/1200x675\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/KQCE5SO2EZB2BDG5UZYXFOD46Q.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/myd6lJbUZT4stwoThaSZZuvp-pc=\/1440x810\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/KQCE5SO2EZB2BDG5UZYXFOD46Q.jpg 1440w\">Los tripulantes<\/p>\n\n\n\n<p>\u201cEste es un momento muy triste para toda la comunidad de exploradores y para cada uno de los familiares de los perdidos en el mar. Pedimos respetuosamente que se respete la privacidad de estas familias durante este momento tan doloroso\u201d, finaliza.<\/p>\n\n\n\n<p>Horas antes, la&nbsp;<strong>Guardia Costera de EEUU<\/strong>&nbsp;anunci\u00f3 que encontraron unos<strong>&nbsp;\u201cescombros<\/strong>\u201d cerca de la zona donde se hallan los restos del&nbsp;<strong>Titanic&nbsp;<\/strong>y donde se est\u00e1n llevando a cabo las labores de b\u00fasqueda para ubicar el sumergible desaparecido.<\/p>\n\n\n\n<p>La Guardia Costera dijo en Twitter que se \u201cha descubierto un campo de escombros dentro del \u00e1rea de b\u00fasqueda cerca del&nbsp;<strong>Titanic<\/strong>\u201d, que se encuentra a una profundidad de unos&nbsp;<strong>3.800 metros.<\/strong><\/p>\n\n\n\n<p>Los expertos de EEUU y Canad\u00e1, reunidos en un centro de coordinaci\u00f3n de operaciones en Boston, est\u00e1n ahora tratando de<strong>&nbsp;determinar a qu\u00e9 corresponden esos escombros<\/strong>&nbsp;y si tienen algo que ver con el sumergible desaparecido.<\/p>\n\n\n\n<p>La b\u00fasqueda, en la que participan barcos, robots y aviones, entr\u00f3 este jueves en una fase cr\u00edtica, pues las 96 horas de ox\u00edgeno de emergencia de que dispon\u00eda el sumergible Titan de la empresa&nbsp;<strong>OceanGate<\/strong>&nbsp;Expeditions se habr\u00edan agotado en la ma\u00f1ana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/elfederalmendoza.com\/wp-content\/uploads\/2023\/06\/oceangate4.jpg\" alt=\"\" class=\"wp-image-24374\" width=\"838\" height=\"557\" srcset=\"https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate4.jpg 691w, https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate4-300x199.jpg 300w\" sizes=\"auto, (max-width: 838px) 100vw, 838px\" \/><figcaption class=\"wp-element-caption\">Momento de su inmersi\u00f3n a las profundidades del Titanic<\/figcaption><\/figure>\n\n\n\n<p>Al cient\u00edfico marino<strong>&nbsp;David Mearns<\/strong>, que conoce a dos de los pasajeros del batiscafo, le embarg\u00f3 el pesimismo tras las palabras utilizadas por los rescatistas.<\/p>\n\n\n\n<p>\u201c<strong>No utilizas expresiones como \u2018campo de restos\u2019 a menos de que no haya posibilidades de encontrar con vida a las personas<\/strong>\u201d, dijo a la cadena&nbsp;<em>Sky News.<\/em><\/p>\n\n\n\n<p>\u201cEsto indica que es el peor de los escenarios,&nbsp;<strong>un fallo catastr\u00f3fico\u201d.<\/strong><\/p>\n\n\n\n<p><em>(Con informaci\u00f3n de AFP)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa OceanGate emiti\u00f3 un comunicado en el que confirm\u00f3 que los cinco tripulantes de Titan, el sumergible que estaba desaparecido desde el domingo, est\u00e1n&nbsp;muertos. \u201cLamentablemente creemos que hemos perdido a nuestro CEO, Stockton Rush, a Shahzada Dawood y a su hijo Suleman Dawood, a Hamish Harding y a Paul-Henri Nargeolet\u201d, se\u00f1al\u00f3 la empresa\u201d, comienza<a class=\"read-more\" href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/2023\/06\/22\/oceangate-que-confirma-la-muerte-de-los-cinco-tripulantes-del-submarino-titan\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":24372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5619],"tags":[],"class_list":["post-24370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"rttpg_featured_image_url":{"full":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3.jpg",1087,605,false],"landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3.jpg",1087,605,false],"portraits":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3.jpg",1087,605,false],"thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3-150x150.jpg",150,150,true],"medium":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3-300x167.jpg",300,167,true],"large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3-1024x570.jpg",640,356,true],"1536x1536":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3.jpg",1087,605,false],"2048x2048":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3.jpg",1087,605,false],"ultp_layout_landscape_large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3.jpg",1087,605,false],"ultp_layout_landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3-870x570.jpg",870,570,true],"ultp_layout_portrait":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3-600x605.jpg",600,605,true],"ultp_layout_square":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3-600x600.jpg",600,600,true],"rpwe-thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3-45x45.jpg",45,45,true],"advps-thumb-one":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/06\/oceangate3-1087x420.jpg",1087,420,true]},"rttpg_author":{"display_name":"Redacci\u00f3n El Federal","author_link":"https:\/\/elfederalmendoza.com.ar\/index.php\/author\/angelflores\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/category\/mundo\/\" rel=\"category tag\">El Mundo<\/a>","rttpg_excerpt":"La empresa OceanGate emiti\u00f3 un comunicado en el que confirm\u00f3 que los cinco tripulantes de Titan, el sumergible que estaba desaparecido desde el domingo, est\u00e1n&nbsp;muertos. \u201cLamentablemente creemos que hemos perdido a nuestro CEO, Stockton Rush, a Shahzada Dawood y a su hijo Suleman Dawood, a Hamish Harding y a Paul-Henri Nargeolet\u201d, se\u00f1al\u00f3 la empresa\u201d, comienza&hellip;","_links":{"self":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/24370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=24370"}],"version-history":[{"count":2,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/24370\/revisions"}],"predecessor-version":[{"id":24379,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/24370\/revisions\/24379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media\/24372"}],"wp:attachment":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=24370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=24370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=24370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}