{"id":27062,"date":"2023-09-04T08:33:30","date_gmt":"2023-09-04T11:33:30","guid":{"rendered":"https:\/\/elfederalmendoza.com\/?p=27062"},"modified":"2023-09-04T08:33:31","modified_gmt":"2023-09-04T11:33:31","slug":"elecciones-municipales-en-mendoza-concurrio-el-695-del-padron-y-estos-fueron-los-ganadores","status":"publish","type":"post","link":"https:\/\/elfederalmendoza.com.ar\/index.php\/2023\/09\/04\/elecciones-municipales-en-mendoza-concurrio-el-695-del-padron-y-estos-fueron-los-ganadores\/","title":{"rendered":"Elecciones municipales en Mendoza: concurri\u00f3 el 69,5% del padr\u00f3n y estos fueron los ganadores"},"content":{"rendered":"\n<p>La votaci\u00f3n en los municipios que adelantaron sus elecciones de intendentes y concejales cerr\u00f3 a las 18. Concurri\u00f3 aproximadamente el 69,5% del padr\u00f3n electoral.<\/p>\n\n\n\n<p>Las cifras\u00a0del conteo de votos correspondiente a las\u00a0<strong>elecciones 2023<\/strong>\u00a0en las 7 comunas que desdoblaron los comicios municipales\u00a0-en su mayor\u00eda en manos del PJ- sugieren triunfos de los\u00a0<strong>oficialismos<\/strong>.<\/p>\n\n\n\n<p>En&nbsp;<strong>Maip\u00fa, San Rafael, La Paz, Santa Rosa, Lavalle y Tunuy\u00e1n<\/strong>&nbsp;el peronismo confirma buenos resultados. En efecto, el candidato a la gobernaci\u00f3n por el Frente Eleg\u00ed,&nbsp;<strong>Omar Parisi<\/strong>, est\u00e1 en camino hacia tierras sanrafaelinas para participar de las celebraciones.<\/p>\n\n\n\n<p>El mismo \u00e1nimo se vive en los b\u00fankeres de\u00a0<strong>Mat\u00edas Stevanato<\/strong>\u00a0(Maip\u00fa) y<strong>\u00a0Emir Andraos<\/strong>\u00a0(Tunuy\u00e1n). En La Paz, Cambia Mendoza ya reconoci\u00f3 la derrota frente al intendente justicialista\u00a0<strong>Fernando Ubieta<\/strong>.<\/p>\n\n\n\n<p>En&nbsp;<strong>San Carlos<\/strong>, Uni\u00f3n Popular -la fuerza de Difonso- tambi\u00e9n anticipa una victoria.<\/p>\n\n\n\n<p>A las 18 cerraron los comicios -se vot\u00f3 con boleta \u00fanica de papel- y se supo que&nbsp;<strong>hab\u00eda concurrido aproximadamente el 69,5% del padr\u00f3n electoral<\/strong>. Esto representa 6% m\u00e1s que la cantidad de personas que fueron a votar durante las elecciones PASO en estos mismos departamentos el pasado 30 de abril, cuando el porcentaje fue del 63,7%.<\/p>\n\n\n\n<p>Para los mendocinos de las comunas que adelantaron sus elecciones para intendentes y concejales, fue la tercera vez que fueron a las urnas este a\u00f1o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las elecciones en Maip\u00fa<\/h2>\n\n\n\n<p>En el b\u00fanker del intendente maipucino,&nbsp;<strong>Mat\u00edas Stevanato (PJ)<\/strong>, hay caras de felicidad desde temprano. El mandatario municipal conf\u00eda en repetir su buena performance de las PASO, cuando sac\u00f3 el 52% de los sufragios. No parece estar muy lejos, ya que&nbsp;<strong>con el 88,64% de las mesas escrutadas obtuvo un 50,64% de los sufragios<\/strong>.<\/p>\n\n\n\n<p>Su principal contrincante,&nbsp;<strong>Mauricio Pinti Clop (UCR),<\/strong>&nbsp;<strong>no logr\u00f3 retener todos los votos que en las PASO fueron para su rival<\/strong>&nbsp;en la interna oficialista, N\u00e9stor Majul.<\/p>\n\n\n\n<p>Pinti Clop levant\u00f3 el&nbsp;<strong>28,61%<\/strong>&nbsp;de los votos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/media.diariouno.com.ar\/p\/e7017a266322c4d9b1424ff576fb5e66\/adjuntos\/298\/imagenes\/009\/220\/0009220599\/1200x0\/smart\/elecciones-municipales-maipu-stevanato-01jpg.jpg\" alt=\"Mat\u00edas Stevanato colocando su voto este domingo 3 de septiembre. \" title=\"\"\/><\/figure>\n\n\n\n<p>Mat\u00edas Stevanato colocando su voto este domingo 3 de septiembre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las elecciones en Tunuy\u00e1n<\/h2>\n\n\n\n<p>En Tunuy\u00e1n,&nbsp;<strong>Emir Andraos<\/strong>&nbsp;(Frente Eleg\u00ed), quien llevaba entre su lista de concejales al intendente&nbsp;<strong>Mart\u00edn Aveiro<\/strong>, se impon\u00eda al candidato&nbsp;<strong>Luis L\u00f3pez<\/strong>&nbsp;(Cambia Mendoza).<\/p>\n\n\n\n<p>Con el 83,85% de las mesas procesadas, Andraos conquist\u00f3 el&nbsp;<strong>53,67%<\/strong>&nbsp;de los votos. Es decir que&nbsp;<strong>Andraos prolongar\u00e1 los 12 a\u00f1os de conducci\u00f3n peronista que concret\u00f3 Aveiro<\/strong>.<\/p>\n\n\n\n<p>El candidato a la vicegobernaci\u00f3n por el Frente Eleg\u00ed,<strong>&nbsp;Lucas Ilardo<\/strong>, ya lleg\u00f3 al Valle de Uco para participar del cierre.<\/p>\n\n\n\n<p><strong>L\u00f3pez<\/strong>, concejal radical en la comuna valletana, fue cuestionado por la Oficina de \u00c9tica P\u00fablica de la provincia por tener dos cargos en el Estado y opt\u00f3 por dejar su trabajo como profesional de la salud y continuar en el Concejo Deliberante tunuyanino.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/media.diariouno.com.ar\/p\/ce5c9279f83bc2af7110520113ae6c80\/adjuntos\/298\/imagenes\/009\/122\/0009122200\/1200x0\/smart\/martin-aveiro-emir-andraos-1jpg.jpg\" alt=\"Mart\u00edn Aveiro junto a Emir Andraos. Dos peronistas ganadores de este domingo. \" title=\"\"\/><\/figure>\n\n\n\n<p>Mart\u00edn Aveiro junto a Emir Andraos. Dos peronistas ganadores de este domingo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las elecciones en La Paz<\/h2>\n\n\n\n<p>En&nbsp;<strong>La Paz<\/strong>&nbsp;el intendente&nbsp;<strong>Fernando Ubieta (PJ)<\/strong>&nbsp;renov\u00f3 su mandato. Pasadas las 20, el exjugador de f\u00fatbol y alba\u00f1il radical&nbsp;<strong>Ramiro Blanco reconoci\u00f3 la derrota.<\/strong><\/p>\n\n\n\n<p>\u00abLa tendencia es&nbsp;<strong>irreversible<\/strong>&nbsp;-dijo el dirigente de Cambia Mendoza-. Nos ponemos a disposici\u00f3n del intendente Ubieta\u00bb.<\/p>\n\n\n\n<p>Con el 72,41% de las mesas escrutadas,<strong>&nbsp;el peronismo ostentaba el 57,02% de los votos<\/strong>, ante el 40,48% del Cambia Mendoza, lo que significa&nbsp;<strong>un panorama distinto a la situaci\u00f3n re\u00f1ida que se hab\u00eda verificado en las PASO locales<\/strong>. Esta vez fue diferente: la tendencia fue claramente favorable al PJ.<\/p>\n\n\n\n<p>As\u00ed las cosas, el departamento del Este, que tiene alrededor de 12.000 habitantes,&nbsp;<strong>seguir\u00e1 en manos del peronismo<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las elecciones en Santa Rosa<\/h2>\n\n\n\n<p>En el caso de&nbsp;<strong>Santa Rosa<\/strong>, la intendenta y presidenta del PJ provincial,&nbsp;<strong>Flor Dest\u00e9fanis<\/strong>, est\u00e1 casi segura de conservar su lugar gan\u00e1ndole a&nbsp;<strong>Leonardo Fern\u00e1ndez<\/strong>, un joven referente surgido del Movimiento de Integraci\u00f3n y Desarrollo, MID, integrado a Cambia Mendoza.<\/p>\n\n\n\n<p>Con el<strong>&nbsp;78,26%<\/strong>&nbsp;de las mesas escrutadas, los guarismos muestran que&nbsp;<strong>Dest\u00e9fanis se hizo con el 56,42% de los votos<\/strong>, frente a un 38,77% que fueron para Fern\u00e1ndez.<\/p>\n\n\n\n<p>De esta forma, Dest\u00e9fanis &#8211;<strong>la \u00fanica intendenta mujer de toda la provincia<\/strong>&#8211; seguir\u00eda a cargo del municipio por 4 a\u00f1os m\u00e1s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las elecciones en San Rafael<\/h2>\n\n\n\n<p>Los hermanos F\u00e9lix&nbsp;<strong>creen que Omar suceder\u00e1 a su hermano Emir en comando del municipio<\/strong>. Es m\u00e1s: el candidato a gobernador por el Frente Eleg\u00ed,&nbsp;<strong>Omar Parisi<\/strong>, estar\u00e1 en su b\u00fanker para intentar una foto de unidad y victoria.<\/p>\n\n\n\n<p><strong>Omar F\u00e9lix<\/strong>, hoy diputado provincial, ya fue intendente de San Rafael en el 2003, y de imponerse este domingo en las urnas vendr\u00eda a garantizar ese enroque entre hermanos que&nbsp;<strong>les permiti\u00f3 mantenerse en el poder por m\u00e1s de 20 a\u00f1os<\/strong>.<\/p>\n\n\n\n<p><strong>\u00abHemos ganado en todas las mesas sanrafaelinas\u00bb<\/strong>, recalc\u00f3 el actual jefe comunal del departamento sure\u00f1o, Emir Felix. Con el 82,12 de las mesas escrutadas, el peronismo ten\u00eda el 48,96% de los votos.<\/p>\n\n\n\n<p>La apuesta del radicalismo recay\u00f3 en el m\u00e9dico y legislador provincial,<strong>&nbsp;Abel Freidemberg (25,99%)<\/strong>, que anteriormente compiti\u00f3 por ese sill\u00f3n y cay\u00f3 derrotado por el mismo Emir.<\/p>\n\n\n\n<p>Pero a la competencia por el sill\u00f3n municipal se prendi\u00f3 con fuerza adem\u00e1s el empresario&nbsp;<strong>Rodolfo Bianchi (20,58%)<\/strong>, que es el candidato libertario y que seg\u00fan las \u00faltimas mediciones ha crecido notoriamente en la intenci\u00f3n de voto.<\/p>\n\n\n\n<p>En San Rafael fue notorio c\u00f3mo Cambia Mendoza&nbsp;<strong>perdi\u00f3 gravitaci\u00f3n respecto a las PASO<\/strong>, acaso por el&nbsp;<strong>\u00abefecto Milei\u00bb<\/strong>&nbsp;que catapult\u00f3 a la opci\u00f3n liberal tras las PASO presidenciales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las elecciones en Lavalle<\/h2>\n\n\n\n<p>En Lavalle fue la primera vez en 22 a\u00f1os en que el intendente saliente&nbsp;<strong>Roberto Righi&nbsp;<\/strong>no estuvo en las listas, con el condimento extra de que el referente cont\u00f3 que har\u00eda campa\u00f1a por La Uni\u00f3n Mendocina, la fuerza de Omar De Marchi, en las elecciones provinciales.<\/p>\n\n\n\n<p>De todos modos, los guarismos muestran que se impuso el candidato del peronismo,&nbsp;<strong>Edgardo Gonz\u00e1lez<\/strong>, quien en abril le gan\u00f3 las internas a Gerardo Vaquer, el hombre por el que apostaba Righi.<\/p>\n\n\n\n<p>Con el 85,32% de las mesas escrutadas,&nbsp;<strong>Gonz\u00e1lez apareci\u00f3 con el 57,44%<\/strong>. Una victoria rotunda.<\/p>\n\n\n\n<p>Segundo -pero lejos- qued\u00f3&nbsp;<strong>Lucas Luppo (27,01%)<\/strong>, el ex concejal radical, y tercero est\u00e1 el Frente Libertario, que llev\u00f3 a&nbsp;<strong>Betina Torrecilla<\/strong>&nbsp;como candidata (11%).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las elecciones en San Carlos<\/h2>\n\n\n\n<p>Con el total de las mesas escrutadas, el frente oficialista de&nbsp;<strong>San Carlos<\/strong>&nbsp;se erige como ganador con el&nbsp;<strong>32% de los sufragios<\/strong>.&nbsp;<strong>Alejandro Morillas<\/strong>&nbsp;(Uni\u00f3n Popular) ser\u00e1 el nuevo jefe comunal.<\/p>\n\n\n\n<p>De todos modos, se verific\u00f3 una elecci\u00f3n de tres tercios.&nbsp;<strong>Silvio Panocchia<\/strong>&nbsp;(UCR-Cambia Mendoza) sac\u00f3 el 29,74% y&nbsp;<strong>Marcelo Romano<\/strong>&nbsp;(Partido Verde) el 28,62%.&nbsp;<strong>Todos quedaron muy cerca<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/media.diariouno.com.ar\/p\/8d277adce95bd8f7968401ba68eced7b\/adjuntos\/298\/imagenes\/009\/220\/0009220807\/1200x0\/smart\/morillas-difonso-demarchijpg.jpg\" alt=\"Jorge Difonso, Omar De Marchi y Alejandro Morillas.&nbsp;\" title=\"\"\/><\/figure>\n\n\n\n<p>Jorge Difonso, Omar De Marchi y Alejandro Morillas.<\/p>\n\n\n\n<p>Como sea, el exintendente&nbsp;<strong>Jorge Difonso<\/strong>&nbsp;seguir\u00e1 siendo una figura de peso por aquellos pagos, luego de que uno de sus aliados,&nbsp;<strong>Rolando Scanio<\/strong>, complete el mandato que est\u00e1 por concluir. La pregunta es qu\u00e9 efecto puede tener todo esto en&nbsp;<strong>La Uni\u00f3n Mendocina<\/strong>, que es la fuerza donde milita el difonsismo actualmente.<\/p>\n\n\n\n<p>El peronismo, por su parte, encara un panorama desafiante, con su candidato&nbsp;<strong>Juanchi Torres<\/strong>&nbsp;alcanzando s\u00f3lo el&nbsp;<strong>4,80%<\/strong>&nbsp;de los votos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La votaci\u00f3n en los municipios que adelantaron sus elecciones de intendentes y concejales cerr\u00f3 a las 18. Concurri\u00f3 aproximadamente el 69,5% del padr\u00f3n electoral. Las cifras\u00a0del conteo de votos correspondiente a las\u00a0elecciones 2023\u00a0en las 7 comunas que desdoblaron los comicios municipales\u00a0-en su mayor\u00eda en manos del PJ- sugieren triunfos de los\u00a0oficialismos. En&nbsp;Maip\u00fa, San Rafael, La<a class=\"read-more\" href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/2023\/09\/04\/elecciones-municipales-en-mendoza-concurrio-el-695-del-padron-y-estos-fueron-los-ganadores\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":27064,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mza"],"rttpg_featured_image_url":{"full":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores.jpg",824,459,false],"landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores.jpg",824,459,false],"portraits":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores.jpg",824,459,false],"thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores-150x150.jpg",150,150,true],"medium":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores-300x167.jpg",300,167,true],"large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores.jpg",640,357,false],"1536x1536":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores.jpg",824,459,false],"2048x2048":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores.jpg",824,459,false],"ultp_layout_landscape_large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores.jpg",824,459,false],"ultp_layout_landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores.jpg",824,459,false],"ultp_layout_portrait":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores-600x459.jpg",600,459,true],"ultp_layout_square":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores-600x459.jpg",600,459,true],"rpwe-thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores-45x45.jpg",45,45,true],"advps-thumb-one":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/ganadores-824x420.jpg",824,420,true]},"rttpg_author":{"display_name":"Redacci\u00f3n El Federal","author_link":"https:\/\/elfederalmendoza.com.ar\/index.php\/author\/angelflores\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/category\/mza\/\" rel=\"category tag\">Mendoza<\/a>","rttpg_excerpt":"La votaci\u00f3n en los municipios que adelantaron sus elecciones de intendentes y concejales cerr\u00f3 a las 18. Concurri\u00f3 aproximadamente el 69,5% del padr\u00f3n electoral. Las cifras\u00a0del conteo de votos correspondiente a las\u00a0elecciones 2023\u00a0en las 7 comunas que desdoblaron los comicios municipales\u00a0-en su mayor\u00eda en manos del PJ- sugieren triunfos de los\u00a0oficialismos. En&nbsp;Maip\u00fa, San Rafael, La&hellip;","_links":{"self":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=27062"}],"version-history":[{"count":1,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27062\/revisions"}],"predecessor-version":[{"id":27065,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27062\/revisions\/27065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media\/27064"}],"wp:attachment":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=27062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=27062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=27062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}