{"id":27074,"date":"2023-09-04T08:15:00","date_gmt":"2023-09-04T11:15:00","guid":{"rendered":"https:\/\/elfederalmendoza.com\/?p=27074"},"modified":"2023-09-04T10:26:09","modified_gmt":"2023-09-04T13:26:09","slug":"el-director-de-la-policia-mendocina-marcelo-calipo-se-suma-al-comando-nacional-antisaqueos","status":"publish","type":"post","link":"https:\/\/elfederalmendoza.com.ar\/index.php\/2023\/09\/04\/el-director-de-la-policia-mendocina-marcelo-calipo-se-suma-al-comando-nacional-antisaqueos\/","title":{"rendered":"El director de la polic\u00eda mendocina, Marcelo Calipo, se suma al comando nacional antisaqueos"},"content":{"rendered":"\n<p>El gobierno de <strong>Rodolfo Su\u00e1rez<\/strong> design\u00f3 al jefe de la Polic\u00eda <strong>Marcelo Calipo<\/strong>, aunque todav\u00eda no hay anuncio oficial.<\/p>\n\n\n\n<p>El comando nacional antisaqueos es el <strong>nuevo organismo que impulsa el ministro de Seguridad<\/strong> de la Naci\u00f3n, An\u00edbal Fern\u00e1ndez.<\/p>\n\n\n\n<p>\u00abEn realidad,<strong> la conformaci\u00f3n del Comando Unificado que dispusieron en Buenos Aires se da ante esta situaci\u00f3n nacional.<\/strong> Se trabaja de forma macro, digamos, pero tiene m\u00e1s que ver con intercambiar informaci\u00f3n\u00bb, explicaron.<\/p>\n\n\n\n<p>Seg\u00fan precisaron, la idea de este nuevo cuerpo es <strong>que Mendoza contin\u00fae enviando informaci\u00f3n <\/strong>sobre c\u00f3mo se mueven los grupos que producen los disturbios y cu\u00e1les son sus caracter\u00edsticas centrales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de Rodolfo Su\u00e1rez design\u00f3 al jefe de la Polic\u00eda Marcelo Calipo, aunque todav\u00eda no hay anuncio oficial. El comando nacional antisaqueos es el nuevo organismo que impulsa el ministro de Seguridad de la Naci\u00f3n, An\u00edbal Fern\u00e1ndez. \u00abEn realidad, la conformaci\u00f3n del Comando Unificado que dispusieron en Buenos Aires se da ante esta situaci\u00f3n<a class=\"read-more\" href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/2023\/09\/04\/el-director-de-la-policia-mendocina-marcelo-calipo-se-suma-al-comando-nacional-antisaqueos\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":27082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mza"],"rttpg_featured_image_url":{"full":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos.jpg",980,640,false],"landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos.jpg",980,640,false],"portraits":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos.jpg",980,640,false],"thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos-150x150.jpg",150,150,true],"medium":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos-300x196.jpg",300,196,true],"large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos.jpg",640,418,false],"1536x1536":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos.jpg",980,640,false],"2048x2048":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos.jpg",980,640,false],"ultp_layout_landscape_large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos.jpg",980,640,false],"ultp_layout_landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos-870x570.jpg",870,570,true],"ultp_layout_portrait":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos-600x640.jpg",600,640,true],"ultp_layout_square":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos-600x600.jpg",600,600,true],"rpwe-thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos-45x45.jpg",45,45,true],"advps-thumb-one":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/09\/Marcelo-Calipo-comando-nacional-antisaqueos-980x420.jpg",980,420,true]},"rttpg_author":{"display_name":"Redacci\u00f3n El Federal","author_link":"https:\/\/elfederalmendoza.com.ar\/index.php\/author\/angelflores\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/category\/mza\/\" rel=\"category tag\">Mendoza<\/a>","rttpg_excerpt":"El gobierno de Rodolfo Su\u00e1rez design\u00f3 al jefe de la Polic\u00eda Marcelo Calipo, aunque todav\u00eda no hay anuncio oficial. El comando nacional antisaqueos es el nuevo organismo que impulsa el ministro de Seguridad de la Naci\u00f3n, An\u00edbal Fern\u00e1ndez. \u00abEn realidad, la conformaci\u00f3n del Comando Unificado que dispusieron en Buenos Aires se da ante esta situaci\u00f3n&hellip;","_links":{"self":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=27074"}],"version-history":[{"count":1,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27074\/revisions"}],"predecessor-version":[{"id":27083,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27074\/revisions\/27083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media\/27082"}],"wp:attachment":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=27074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=27074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=27074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}