{"id":29335,"date":"2023-11-09T17:45:21","date_gmt":"2023-11-09T20:45:21","guid":{"rendered":"https:\/\/elfederalmendoza.com\/?p=29335"},"modified":"2023-11-09T17:46:22","modified_gmt":"2023-11-09T20:46:22","slug":"bombos-y-hombres-motosierra-la-bienvenida-a-milei-en-mendoza","status":"publish","type":"post","link":"https:\/\/elfederalmendoza.com.ar\/index.php\/2023\/11\/09\/bombos-y-hombres-motosierra-la-bienvenida-a-milei-en-mendoza\/","title":{"rendered":"Bombos y \u00abhombres motosierra\u00bb: la bienvenida a Milei en Mendoza"},"content":{"rendered":"\n<p>Siguen llegando seguidores de&nbsp;<strong>Javier Milei a la sede del PD<\/strong>, donde deber\u00eda comenzar el recorrido hacia Plaza Independencia. El libertario a\u00fan no aparece. La mayor\u00eda de los presentes se identifica con consignas del Partido Dem\u00f3crata. Hay bombos, redoblantes, disfraces de motosierra, el disfrazado de le\u00f3n y m\u00e1s.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/527\/527311\/654d40ed04edf_570_261!.jpg?s=c1d8478be2c17a990a15ba3e34b0b0b3&amp;d=1699561712\" alt=\"\" width=\"837\" height=\"383\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/527\/527309\/654d407a3c8b5_570_261!.jpg?s=93cf616a1bd240d16acc2856c8bc8bdf&amp;d=1699561691\" alt=\"\" width=\"839\" height=\"384\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/527\/527313\/654d4152385cb_570_261!.jpg?s=2566400ac55b35c75d48740e60050104&amp;d=1699561813\" alt=\"\" width=\"836\" height=\"383\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>17.07 horas<\/strong><\/h2>\n\n\n\n<p><strong>Javier Milei,<\/strong>&nbsp;candidato a presidente de&nbsp;<strong>La Libertad Avanza<\/strong>, lleg\u00f3 este jueves a&nbsp;<strong>Mendoza<\/strong>, en lo que ser\u00e1 su \u00faltimo acto de campa\u00f1a en la provincia previo al balotaje del 19 de noviembre.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">As\u00ed esperan por Milei en la sede del PD de Mendoza. Encabezar\u00e1 una caminata rumbo a Plaza Independencia <a href=\"https:\/\/t.co\/bWbOaCNnUD\">pic.twitter.com\/bWbOaCNnUD<\/a><\/p>&mdash; Mendoza Post (@MendozaPost) <a href=\"https:\/\/twitter.com\/MendozaPost\/status\/1722708112644210999?ref_src=twsrc%5Etfw\">November 9, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p>Milei arrib\u00f3 a Mendoza en un vuelo de&nbsp;<strong>Flybondi<\/strong>, hace un par de horas. A las 17 estaba previsto que comenzara una caminata desde la sede del PD hasta Plaza Independencia, pero se ha demorado.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">Bombos, redoblantes y &quot;hombres motosierra&quot;, parte del cotill\u00f3n de bienvenida de Milei en Mendoza <a href=\"https:\/\/t.co\/BODLWVjlmY\">pic.twitter.com\/BODLWVjlmY<\/a><\/p>&mdash; Mendoza Post (@MendozaPost) <a href=\"https:\/\/twitter.com\/MendozaPost\/status\/1722710495415681048?ref_src=twsrc%5Etfw\">November 9, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p><strong>As\u00ed lo esperan sus seguidores en la sede del PD:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/527\/527307\/654d3fdd62050_570_425!.jpg?s=f8335ea9a07e234a1b12c5a493088311&amp;d=1699561440\" alt=\"\" width=\"842\" height=\"628\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/527\/527297\/654d3c2cbd733_570_425!.jpg?s=79caff752195bf295eb584a01930bc91&amp;d=1699560495\" alt=\"\" width=\"838\" height=\"625\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/527\/527299\/654d3c366e800_570_425!.jpg?s=6f70abfdbe41e931c580b76fbff4ed1e&amp;d=1699560505\" alt=\"\" width=\"837\" height=\"624\"\/><\/figure>\n\n\n\n<p>16.34<\/p>\n\n\n\n<p>En&nbsp;<strong>Plaza Independencia<\/strong>&nbsp;montaron una&nbsp;<strong>pantalla<\/strong>&nbsp;frente al cartel de \u00abMendoza\u00bb, hasta donde llegar\u00e1 m\u00e1s tarde Javier Milei y sus seguidores. Lo acompa\u00f1ar\u00e1, entre otros, Mercedes Llano, diputada nacional electa por La Libertad Avanza.<\/p>\n\n\n\n<p>14.05<\/p>\n\n\n\n<p>En la previa de la llegada de Milei a Mendoza, desconocidos vandalizaron la sede del Partido Dem\u00f3crata, donde empezar\u00e1 el recorrido del libertario rumbo a Plaza Independencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siguen llegando seguidores de&nbsp;Javier Milei a la sede del PD, donde deber\u00eda comenzar el recorrido hacia Plaza Independencia. El libertario a\u00fan no aparece. La mayor\u00eda de los presentes se identifica con consignas del Partido Dem\u00f3crata. Hay bombos, redoblantes, disfraces de motosierra, el disfrazado de le\u00f3n y m\u00e1s. 17.07 horas Javier Milei,&nbsp;candidato a presidente de&nbsp;La Libertad<a class=\"read-more\" href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/2023\/11\/09\/bombos-y-hombres-motosierra-la-bienvenida-a-milei-en-mendoza\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":29337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mza"],"rttpg_featured_image_url":{"full":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra.jpg",873,456,false],"landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra.jpg",873,456,false],"portraits":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra.jpg",873,456,false],"thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra-150x150.jpg",150,150,true],"medium":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra-300x157.jpg",300,157,true],"large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra.jpg",640,334,false],"1536x1536":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra.jpg",873,456,false],"2048x2048":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra.jpg",873,456,false],"ultp_layout_landscape_large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra.jpg",873,456,false],"ultp_layout_landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra-870x456.jpg",870,456,true],"ultp_layout_portrait":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra-600x456.jpg",600,456,true],"ultp_layout_square":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra-600x456.jpg",600,456,true],"rpwe-thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra-45x45.jpg",45,45,true],"advps-thumb-one":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/motosierra-873x420.jpg",873,420,true]},"rttpg_author":{"display_name":"Redacci\u00f3n El Federal","author_link":"https:\/\/elfederalmendoza.com.ar\/index.php\/author\/angelflores\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/category\/mza\/\" rel=\"category tag\">Mendoza<\/a>","rttpg_excerpt":"Siguen llegando seguidores de&nbsp;Javier Milei a la sede del PD, donde deber\u00eda comenzar el recorrido hacia Plaza Independencia. El libertario a\u00fan no aparece. La mayor\u00eda de los presentes se identifica con consignas del Partido Dem\u00f3crata. Hay bombos, redoblantes, disfraces de motosierra, el disfrazado de le\u00f3n y m\u00e1s. 17.07 horas Javier Milei,&nbsp;candidato a presidente de&nbsp;La Libertad&hellip;","_links":{"self":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/29335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=29335"}],"version-history":[{"count":2,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/29335\/revisions"}],"predecessor-version":[{"id":29341,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/29335\/revisions\/29341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media\/29337"}],"wp:attachment":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=29335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=29335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=29335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}