{"id":29362,"date":"2023-11-10T14:13:40","date_gmt":"2023-11-10T17:13:40","guid":{"rendered":"https:\/\/elfederalmendoza.com\/?p=29362"},"modified":"2023-11-10T14:13:41","modified_gmt":"2023-11-10T17:13:41","slug":"mendoza-pidio-a-la-corte-suprema-que-declare-la-inconstitucionalidad-del-aumento-del-piso-para-pagar-impuesto-a-las-ganancias","status":"publish","type":"post","link":"https:\/\/elfederalmendoza.com.ar\/index.php\/2023\/11\/10\/mendoza-pidio-a-la-corte-suprema-que-declare-la-inconstitucionalidad-del-aumento-del-piso-para-pagar-impuesto-a-las-ganancias\/","title":{"rendered":"Mendoza pidi\u00f3 a la Corte Suprema que declare la inconstitucionalidad del aumento del piso para pagar impuesto a las ganancias"},"content":{"rendered":"\n<p>El<strong>\u00a0Gobierno provincial\u00a0<\/strong>llev\u00f3 a la<strong>\u00a0Corte Suprema de Justicia\u00a0<\/strong>su reclamo por la p\u00e9rdida de\u00a0<strong>$7 mil millones en t\u00e9rminos de coparticipaci\u00f3n\u00a0<\/strong>por la modificaci\u00f3n del\u00a0<strong>Impuesto a las Ganancias<\/strong>, aprobada en el Congreso y motorizada por el ministro de Econom\u00eda y candidato presidencial,<strong>\u00a0Sergio Massa.<\/strong><\/p>\n\n\n\n<p>El gobernador&nbsp;<strong>Rodolfo Su\u00e1rez&nbsp;<\/strong>anunci\u00f3 este viernes que elevaron un acci\u00f3n de inconstitucionalidad con una medida cautelar ante el m\u00e1ximo tribunal, es decir que se deje sin efecto su aplicaci\u00f3n hasta que se resuelva la cuesti\u00f3n de fondo.<\/p>\n\n\n\n<p>\u201cPresentamos una acci\u00f3n de inconstitucionalidad junto con una medida cautelar ante la Corte Suprema de Justicia de la Naci\u00f3n, en respuesta al decreto y a la modificaci\u00f3n de la Ley de Impuesto a las Ganancias, medidas que<strong>\u00a0impactan negativamente en las finanzas de Mendoza<\/strong>\u201d, public\u00f3 el mandatario provincial en redes sociales.<\/p>\n\n\n\n<p>Luego, afirm\u00f3 que \u201cel Decreto N\u00ba 473\/2023 del Gobierno Nacional, emitido el 12 de septiembre, supuso<strong>\u00a0una p\u00e9rdida de aproximadamente $7.000 millones\u00a0<\/strong>en concepto de coparticipaci\u00f3n para Mendoza entre octubre y noviembre\u201d.<\/p>\n\n\n\n<p>\u201cAdem\u00e1s, ante la modificaci\u00f3n de la Ley 27.725 que estar\u00e1 vigente desde 2024, la provincia deber\u00e1 enfrentar<strong>\u00a0una p\u00e9rdida de ingresos por 1.700 millones de pesos\u00a0<\/strong>aproximadamente\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Y asver\u00f3: \u201cTanto el decreto como la ley son inconstitucionales, ya que disminuyen unilateralmente la percepci\u00f3n de impuestos que integran la masa coparticipable, afectando el federalismo fiscal y perjudicando a Mendoza\u201d.<\/p>\n\n\n\n<p>\u201cMendoza se convierte en la primera jurisdicci\u00f3n en oponerse legalmente a la<strong>&nbsp;Reforma Tributaria Nacional&nbsp;<\/strong>impulsada por el Gobierno Nacional. Esta decisi\u00f3n es respaldada por otros gobernadores de Juntos por el Cambio, quienes planean hacer lo mismo en sus respectivas provincias\u201d, asegur\u00f3 alentando a que m\u00e1s provincias se sumen.<\/p>\n\n\n\n<p>Y dijo que adem\u00e1s de la acci\u00f3n de inconstitucionalidad, le solicitaron a la Corte que exija al Estado Nacional que \u201ccompense las p\u00e9rdidas causadas por esta reforma tributaria con sus propios fondos\u201d.<\/p>\n\n\n\n<p>\u201cEl objetivo es que la Naci\u00f3n asuma la responsabilidad de las consecuencias de sus decisiones tributarias sin aumentar la carga fiscal de los ciudadanos\u201d, complet\u00f3 el gobernador en su extenso hilo de X.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0Gobierno provincial\u00a0llev\u00f3 a la\u00a0Corte Suprema de Justicia\u00a0su reclamo por la p\u00e9rdida de\u00a0$7 mil millones en t\u00e9rminos de coparticipaci\u00f3n\u00a0por la modificaci\u00f3n del\u00a0Impuesto a las Ganancias, aprobada en el Congreso y motorizada por el ministro de Econom\u00eda y candidato presidencial,\u00a0Sergio Massa. El gobernador&nbsp;Rodolfo Su\u00e1rez&nbsp;anunci\u00f3 este viernes que elevaron un acci\u00f3n de inconstitucionalidad con una medida cautelar ante<a class=\"read-more\" href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/2023\/11\/10\/mendoza-pidio-a-la-corte-suprema-que-declare-la-inconstitucionalidad-del-aumento-del-piso-para-pagar-impuesto-a-las-ganancias\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":29364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mza"],"rttpg_featured_image_url":{"full":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg.webp",1200,700,false],"landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg.webp",1200,700,false],"portraits":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg.webp",1200,700,false],"thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg-150x150.webp",150,150,true],"medium":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg-300x175.webp",300,175,true],"large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg-1024x597.webp",640,373,true],"1536x1536":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg.webp",1200,700,false],"2048x2048":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg.webp",1200,700,false],"ultp_layout_landscape_large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg.webp",1200,700,false],"ultp_layout_landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg-870x570.webp",870,570,true],"ultp_layout_portrait":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg-600x700.webp",600,700,true],"ultp_layout_square":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg-600x600.webp",600,600,true],"rpwe-thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg-45x45.webp",45,45,true],"advps-thumb-one":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2023\/11\/rodolfo-suarez-sergio-massajpg-1200x420.webp",1200,420,true]},"rttpg_author":{"display_name":"Redacci\u00f3n El Federal","author_link":"https:\/\/elfederalmendoza.com.ar\/index.php\/author\/angelflores\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/category\/mza\/\" rel=\"category tag\">Mendoza<\/a>","rttpg_excerpt":"El\u00a0Gobierno provincial\u00a0llev\u00f3 a la\u00a0Corte Suprema de Justicia\u00a0su reclamo por la p\u00e9rdida de\u00a0$7 mil millones en t\u00e9rminos de coparticipaci\u00f3n\u00a0por la modificaci\u00f3n del\u00a0Impuesto a las Ganancias, aprobada en el Congreso y motorizada por el ministro de Econom\u00eda y candidato presidencial,\u00a0Sergio Massa. El gobernador&nbsp;Rodolfo Su\u00e1rez&nbsp;anunci\u00f3 este viernes que elevaron un acci\u00f3n de inconstitucionalidad con una medida cautelar ante&hellip;","_links":{"self":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/29362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=29362"}],"version-history":[{"count":1,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/29362\/revisions"}],"predecessor-version":[{"id":29365,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/29362\/revisions\/29365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media\/29364"}],"wp:attachment":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=29362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=29362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=29362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}