{"id":34999,"date":"2025-10-11T07:30:07","date_gmt":"2025-10-11T10:30:07","guid":{"rendered":"https:\/\/elfederalmendoza.com.ar\/?p=34999"},"modified":"2025-10-11T07:40:48","modified_gmt":"2025-10-11T10:40:48","slug":"argentina-se-proyecta-como-lider-mundial-de-ia-asi-es-el-plan-de-openai-en-el-pais","status":"publish","type":"post","link":"https:\/\/elfederalmendoza.com.ar\/index.php\/2025\/10\/11\/argentina-se-proyecta-como-lider-mundial-de-ia-asi-es-el-plan-de-openai-en-el-pais\/","title":{"rendered":"Argentina se proyecta como l\u00edder mundial de IA: as\u00ed es el plan de OpenAI en el pa\u00eds"},"content":{"rendered":"\n<p><strong>Este viernes, OpenAI anunci\u00f3 una\u00a0inversi\u00f3n hist\u00f3rica en Argentina\u00a0de US$25.000 millones<\/strong>. La empresa creadora del Chat GPT confirm\u00f3 la construcci\u00f3n de un\u00a0<strong>centro de datos de inteligencia artificial ubicado en la Patagonia<\/strong>,\u00a0que ser\u00e1 el primero de este tipo en Am\u00e9rica Latina.<\/p>\n\n\n\n<p>El proyecto, denominado&nbsp;<strong>Stargate Argentina<\/strong>, se desarrollar\u00e1 en colaboraci\u00f3n con&nbsp;<strong>Sur Energy<\/strong>, la empresa fundada por los argentinos&nbsp;<strong>Mat\u00edas Travizano<\/strong>&nbsp;y&nbsp;<strong>Emiliano Kargieman<\/strong>, especializada en infraestructura y energ\u00eda. Su capacidad alcanzar\u00e1&nbsp;<strong>500 MW<\/strong>, lo que permitir\u00e1 ampliar la capacidad de procesamiento de OpenAI y mejorar sus sistemas de IA.<\/p>\n\n\n\n<p>El anuncio fue realizado por el CEO de OpenAI,\u00a0<strong>Sam Altman<\/strong>, quien destac\u00f3 que la meta es convertir a Argentina \u00aben un centro de inteligencia artificial para toda Am\u00e9rica Latina\u00bb. Altman tambi\u00e9n resalt\u00f3 la visi\u00f3n del presidente\u00a0<strong>Javier Milei<\/strong>, a quien conoci\u00f3 el a\u00f1o pasado en Estados Unidos, sobre c\u00f3mo la IA puede impulsar \u00abel crecimiento y la creatividad de la Argentina\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/676\/676459\/68e98dc67cf41_570_380!.jpg?s=a16b1699df0f23be9319e15afacc1eb5&amp;d=1760136649\" alt=\"\" style=\"width:840px;height:auto\"\/><figcaption class=\"wp-element-caption\">Javier Milei recibi\u00f3 este viernes a representantes de OpenAI en la Casa Rosada.<\/figcaption><\/figure>\n\n\n\n<p>Tras el encuentro en la&nbsp;<strong>Casa Rosada<\/strong>&nbsp;entre Milei, el presidente de Nucleoel\u00e9ctrica Argentina&nbsp;<strong>Demian Reidel<\/strong>&nbsp;y representantes de OpenAI, el Gobierno se\u00f1al\u00f3 que se trata de \u00abun proyecto pionero de infraestructura de inteligencia artificial que situar\u00e1 a la Argentina a la vanguardia del ecosistema global\u00bb.<\/p>\n\n\n\n<p><strong>Una obra que comenzar\u00e1 en 2026<\/strong><\/p>\n\n\n\n<p>Se prev\u00e9 que la&nbsp;<strong>primera parte del data center comience a construirse el pr\u00f3ximo a\u00f1o<\/strong>&nbsp;y est\u00e9 terminada&nbsp;<strong>12 meses despu\u00e9s<\/strong>.&nbsp;<strong>Sur Energy<\/strong>&nbsp;ser\u00e1 la encargada de financiar la iniciativa junto a un socio proveedor de desarrollos en la nube -cuyo nombre a\u00fan no trascendi\u00f3- y a&nbsp;<strong>empresas energ\u00e9ticas locales<\/strong>&nbsp;que aportar\u00e1n infraestructura.<\/p>\n\n\n\n<p>Por su parte,&nbsp;<strong>OpenAI ser\u00e1 el offtaker<\/strong>, es decir, el&nbsp;<strong>comprador de toda la potencia computacional<\/strong>&nbsp;que la instalaci\u00f3n genere. Su compromiso de adquisici\u00f3n garantiza la viabilidad del proyecto, aun sin ser el inversor directo.<\/p>\n\n\n\n<p>Si bien OpenAI tiene proyectos similares en&nbsp;<strong>Alemania, Noruega, Jap\u00f3n y Corea<\/strong>, el de&nbsp;<strong>Argentina ser\u00e1 el m\u00e1s grande hasta el momento.<\/strong><\/p>\n\n\n\n<p>Prev\u00e9n ejecutar la inversi\u00f3n&nbsp;<strong>en varias etapas<\/strong>, con un&nbsp;<strong>primer tramo de entre US$7.000 y US$10.000 millones<\/strong>, seg\u00fan pudo saber&nbsp;<em>Infobae<\/em>. Adem\u00e1s, se analizan&nbsp;<strong>cinco posibles locaciones en la Patagonia<\/strong>, cuyos nombres a\u00fan no fueron revelados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qu\u00e9 es Stargate&nbsp;<\/strong><\/h2>\n\n\n\n<p>El proyecto&nbsp;<strong>Stargate<\/strong>&nbsp;fue lanzado a comienzos de 2025 y es impulsado por OpenAI junto a empresas como&nbsp;<strong>SoftBank, Oracle, MGX, Arm y Microsoft<\/strong>. La iniciativa busca invertir&nbsp;<strong>US$500.000 millones<\/strong>&nbsp;en la construcci\u00f3n de centros de datos que aumenten la capacidad de procesamiento de OpenAI y fortalezcan la inteligencia artificial a nivel global.<\/p>\n\n\n\n<p>\u00abLa IA solo podr\u00e1 hacer realidad sus promesas si desarrollamos la capacidad inform\u00e1tica necesaria para impulsarla. Esa es la clave para garantizar que todo el mundo pueda beneficiarse de la IA y abrir la puerta a futuros avances\u00bb, afirm\u00f3&nbsp;<strong>Altman<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El rol crucial del RIGI&nbsp;<\/strong><\/h2>\n\n\n\n<p>El proyecto se inscribe dentro del&nbsp;<strong>R\u00e9gimen de Incentivos a las Grandes Inversiones (RIGI)<\/strong>, que ofrece beneficios fiscales, aduaneros y cambiarios para inversiones superiores a&nbsp;<strong>US$200 millones<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" src=\"https:\/\/www.mendozapost.com\/files\/image\/676\/676463\/68e98f0bc6379_570_380!.jpg?s=c37b75bafb55494d0b88ff3bae046c67&amp;d=1760136974\" alt=\"\" style=\"width:840px;height:auto\"\/><figcaption class=\"wp-element-caption\">Sam Altman anunci\u00f3 la inversi\u00f3n de US$25.000 millones en Argentina.<\/figcaption><\/figure>\n\n\n\n<p>Seg\u00fan el\u00a0<strong>jefe de Gabinete\u00a0Guillermo Francos<\/strong>, ya se presentaron 20 proyectos bajo el RIGI, de los cuales se aprobaron 5 por casi\u00a0<strong>US$13.000 millones<\/strong>, sum\u00e1ndose recientemente un proyecto minero en San Juan por\u00a0<strong>US$2.700 millones<\/strong>.<\/p>\n\n\n\n<p>Un informe de la&nbsp;<strong>Universidad Austral<\/strong>&nbsp;indica que el RIGI ha recibido proyectos por cerca de&nbsp;<strong>US$35.000 millones<\/strong>, principalmente en sectores estrat\u00e9gicos como la energ\u00eda y la miner\u00eda.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes, OpenAI anunci\u00f3 una\u00a0inversi\u00f3n hist\u00f3rica en Argentina\u00a0de US$25.000 millones. La empresa creadora del Chat GPT confirm\u00f3 la construcci\u00f3n de un\u00a0centro de datos de inteligencia artificial ubicado en la Patagonia,\u00a0que ser\u00e1 el primero de este tipo en Am\u00e9rica Latina. El proyecto, denominado&nbsp;Stargate Argentina, se desarrollar\u00e1 en colaboraci\u00f3n con&nbsp;Sur Energy, la empresa fundada por los argentinos&nbsp;Mat\u00edas<a class=\"read-more\" href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/2025\/10\/11\/argentina-se-proyecta-como-lider-mundial-de-ia-asi-es-el-plan-de-openai-en-el-pais\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":35000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5618],"tags":[],"class_list":["post-34999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arg"],"rttpg_featured_image_url":{"full":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai.jpg",1185,782,false],"landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai.jpg",1185,782,false],"portraits":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai.jpg",1185,782,false],"thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai-150x150.jpg",150,150,true],"medium":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai-300x198.jpg",300,198,true],"large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai-1024x676.jpg",640,423,true],"1536x1536":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai.jpg",1185,782,false],"2048x2048":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai.jpg",1185,782,false],"ultp_layout_landscape_large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai.jpg",1185,782,false],"ultp_layout_landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai-870x570.jpg",870,570,true],"ultp_layout_portrait":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai-600x782.jpg",600,782,true],"ultp_layout_square":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai-600x600.jpg",600,600,true],"rpwe-thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai-45x45.jpg",45,45,true],"advps-thumb-one":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2025\/10\/openai-1185x420.jpg",1185,420,true]},"rttpg_author":{"display_name":"Redacci\u00f3n El Federal","author_link":"https:\/\/elfederalmendoza.com.ar\/index.php\/author\/angelflores\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/category\/arg\/\" rel=\"category tag\">Argentina<\/a>","rttpg_excerpt":"Este viernes, OpenAI anunci\u00f3 una\u00a0inversi\u00f3n hist\u00f3rica en Argentina\u00a0de US$25.000 millones. La empresa creadora del Chat GPT confirm\u00f3 la construcci\u00f3n de un\u00a0centro de datos de inteligencia artificial ubicado en la Patagonia,\u00a0que ser\u00e1 el primero de este tipo en Am\u00e9rica Latina. El proyecto, denominado&nbsp;Stargate Argentina, se desarrollar\u00e1 en colaboraci\u00f3n con&nbsp;Sur Energy, la empresa fundada por los argentinos&nbsp;Mat\u00edas&hellip;","_links":{"self":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/34999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=34999"}],"version-history":[{"count":1,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/34999\/revisions"}],"predecessor-version":[{"id":35001,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/34999\/revisions\/35001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media\/35000"}],"wp:attachment":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=34999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=34999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=34999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}