{"id":4350,"date":"2021-09-30T11:20:51","date_gmt":"2021-09-30T14:20:51","guid":{"rendered":"https:\/\/elfederalmendoza.com\/?p=4350"},"modified":"2021-11-29T20:36:00","modified_gmt":"2021-11-29T23:36:00","slug":"comienza-el-apagon-de-internet-que-dispositivos-seran-afectados-a-partir-de-hoy","status":"publish","type":"post","link":"https:\/\/elfederalmendoza.com.ar\/index.php\/2021\/09\/30\/comienza-el-apagon-de-internet-que-dispositivos-seran-afectados-a-partir-de-hoy\/","title":{"rendered":"Comienza el apag\u00f3n de internet: Qu\u00e9 dispositivos ser\u00e1n afectados a partir de hoy"},"content":{"rendered":"\n<p>Todos los dispositivos que cuenten con ese certificado root perder\u00e1n su conectividad, a menos que puedan actualizarlo.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tel\u00e9fonos con&nbsp;<strong>Android 2.3.6 Gingerbread o versiones anteriores&nbsp;<\/strong>se ver\u00e1n afectados.<\/li><li>En Apple los iPhone o iPad que est\u00e9n usando&nbsp;<strong>la versi\u00f3n 9 del sistema operativo iOS<\/strong>&nbsp;o anteriores. (El iphone 5 ser\u00eda el modelo m\u00e1s antiguo que puede tener iOS 10).<\/li><li><strong>Windows XP con actualizaci\u00f3n anteriores Service Pack 3<\/strong><\/li><li><strong>PlayStation 3 con firmware versi\u00f3n 5.0 o anteriores y algunas Nintendo 3DS<\/strong>. Las consolas PS4 con firmware anterior al 5.0 (no deber\u00eda ser ninguna sin fueron actualizadas regularmente).<\/li><\/ul>\n\n\n\n<p>El 30 de septiembre vence un certificado de autenticaci\u00f3n, que valida la conexi\u00f3n de los equipos. Consolas de videojuegos, computadoras y celulares antiguos se ver\u00e1n afectados.<\/p>\n\n\n\n<p>Hoy es el d\u00eda clave, un particular fen\u00f3meno que fue bautizado como<strong>&nbsp;apag\u00f3n de&nbsp;Internet: miles de dispositivos quedar\u00e1n desconectados&nbsp;<\/strong>por el vencimiento de un certificado de autenticaci\u00f3n necesario para validar la conexi\u00f3n de un dispositivo con el servidor base. Dicho de otra forma: los que no puedan actualizarlo se quedar\u00e1n sin Internet a partir del 30 de septiembre.<\/p>\n\n\n\n<p>Los afectados son diversos dispositivos electr\u00f3nicos con acceso a la Web, como celulares, consolas de videojuegos, televisores smart y computadoras. Todos estos aparatos realizan una conexi\u00f3n con un servider Web que lleva a cabo una serie de procesos para<strong>&nbsp;validar la seguridad<\/strong>. El \u00faltimo paso son los certificados root, el eje del conflicto.<\/p>\n\n\n\n<p>Un investigador, Scott Helme, inform\u00f3 que&nbsp;<strong>el 30 de septiembre dejar\u00e1 de estar activo el certificado ra\u00edz de HTTPS IdentTrust DST Root CA X3,&nbsp;<\/strong>principalmente usado por la autoridad de certificaci\u00f3n sin \u00e1nimo de lucro Let\u2019s Encrypt. As\u00ed&nbsp;lo inform\u00f3&nbsp;el portal especializado en tecnolog\u00eda&nbsp;<em>Tech Crunch<\/em>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 dispositivos ser\u00e1n afectados por el apag\u00f3n de Internet<\/h2>\n\n\n\n<p>Todos los dispositivos que cuenten con ese certificado root perder\u00e1n su conectividad, a menos que puedan actualizarlo.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tel\u00e9fonos con&nbsp;<strong>Android 2.3.6 Gingerbread o versiones anteriores&nbsp;<\/strong>se ver\u00e1n afectados.<\/li><li>En Apple los iPhone o iPad que est\u00e9n usando&nbsp;<strong>la versi\u00f3n 9 del sistema operativo iOS<\/strong>&nbsp;o anteriores. (El iphone 5 ser\u00eda el modelo m\u00e1s antiguo que puede tener iOS 10).<\/li><li><strong>Windows XP con actualizaci\u00f3n anteriores Service Pack 3<\/strong><\/li><li><strong>PlayStation 3 con firmware versi\u00f3n 5.0 o anteriores y algunas Nintendo 3DS<\/strong>. Las consolas PS4 con firmware anterior al 5.0 (no deber\u00eda ser ninguna sin fueron actualizadas regularmente).<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Todos los dispositivos que cuenten con ese certificado root perder\u00e1n su conectividad, a menos que puedan actualizarlo. Tel\u00e9fonos con&nbsp;Android 2.3.6 Gingerbread o versiones anteriores&nbsp;se ver\u00e1n afectados. En Apple los iPhone o iPad que est\u00e9n usando&nbsp;la versi\u00f3n 9 del sistema operativo iOS&nbsp;o anteriores. (El iphone 5 ser\u00eda el modelo m\u00e1s antiguo que puede tener iOS 10).<a class=\"read-more\" href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/2021\/09\/30\/comienza-el-apagon-de-internet-que-dispositivos-seran-afectados-a-partir-de-hoy\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":4352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mza"],"rttpg_featured_image_url":{"full":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1.jpg",626,417,false],"landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1.jpg",626,417,false],"portraits":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1.jpg",626,417,false],"thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1-150x150.jpg",150,150,true],"medium":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1-300x200.jpg",300,200,true],"large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1.jpg",626,417,false],"1536x1536":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1.jpg",626,417,false],"2048x2048":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1.jpg",626,417,false],"ultp_layout_landscape_large":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1.jpg",626,417,false],"ultp_layout_landscape":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1.jpg",626,417,false],"ultp_layout_portrait":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1-600x417.jpg",600,417,true],"ultp_layout_square":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1-600x417.jpg",600,417,true],"rpwe-thumbnail":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1-45x45.jpg",45,45,true],"advps-thumb-one":["https:\/\/elfederalmendoza.com.ar\/wp-content\/uploads\/2021\/09\/APAGON1.jpg",626,417,false]},"rttpg_author":{"display_name":"Redacci\u00f3n El Federal","author_link":"https:\/\/elfederalmendoza.com.ar\/index.php\/author\/angelflores\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/elfederalmendoza.com.ar\/index.php\/category\/mza\/\" rel=\"category tag\">Mendoza<\/a>","rttpg_excerpt":"Todos los dispositivos que cuenten con ese certificado root perder\u00e1n su conectividad, a menos que puedan actualizarlo. Tel\u00e9fonos con&nbsp;Android 2.3.6 Gingerbread o versiones anteriores&nbsp;se ver\u00e1n afectados. En Apple los iPhone o iPad que est\u00e9n usando&nbsp;la versi\u00f3n 9 del sistema operativo iOS&nbsp;o anteriores. (El iphone 5 ser\u00eda el modelo m\u00e1s antiguo que puede tener iOS 10).&hellip;","_links":{"self":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=4350"}],"version-history":[{"count":2,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4350\/revisions"}],"predecessor-version":[{"id":4420,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4350\/revisions\/4420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media\/4352"}],"wp:attachment":[{"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=4350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=4350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfederalmendoza.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=4350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}